{"id":2716,"date":"2022-08-04T17:44:22","date_gmt":"2022-08-04T15:44:22","guid":{"rendered":"https:\/\/gardiso.insektenschutz365.eu\/p\/sandkasten-vlies\/"},"modified":"2025-12-30T06:39:18","modified_gmt":"2025-12-30T05:39:18","slug":"sandkasten-vlies","status":"publish","type":"product","link":"https:\/\/www.gardiso.eu\/de\/p\/sandkasten-vlies\/","title":{"rendered":"Sandkasten-Vlies"},"content":{"rendered":"<h4>Vlieseinlage f&uuml;r Sandk&auml;sten<\/h4>\n<p><strong>Zur sauberen Trennung unterschiedlicher Schichten<\/strong><br \/>\n&nbsp;<\/p>\n<p>Das robuste und verrottungsresistente&nbsp;Gewebe ist ideal f&uuml;r die Anwendung in Sandk&auml;sten. Es wirkt wie ein Filter und sch&uuml;tzt den Sand vor Vermischung mit Erde. Damit ist der Spielsand l&auml;nger sauber und verwendbar. Es h&auml;lt auch Unkraut und sonstige Verunreinigungen zuverl&auml;ssig vom Sandkasten fern.&nbsp;<\/p>\n<p>\n<strong>Eckdaten<\/strong><\/p>\n<ul>\n<li>Gr&ouml;&szlig;e:&nbsp;2 x 2 m<\/li>\n<li>St&auml;rke: 90 g\/m&sup2;<\/li>\n<li>Farbe: beige<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Lieferumfang<\/strong><\/p>\n<ul>\n<li>2m Vliesrolle<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><UL><LI>Vlies-Einlage f\u00fcr den Sandkasten<\/LI><LI>Ideal zur Trennung von Sand und Erde<\/LI><LI>L\u00e4ngere Verwendbarkeit von Spielsand m\u00f6glich<\/LI><LI>Unkrautwuchs wird vermindert<\/LI><\/UL><\/p>\n","protected":false},"featured_media":1301,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[935,934],"product_tag":[],"wcpa_form_fields":null,"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"_links":{"self":[{"href":"https:\/\/www.gardiso.eu\/de\/wp-json\/wp\/v2\/product\/2716"}],"collection":[{"href":"https:\/\/www.gardiso.eu\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.gardiso.eu\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gardiso.eu\/de\/wp-json\/wp\/v2\/comments?post=2716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gardiso.eu\/de\/wp-json\/wp\/v2\/media\/1301"}],"wp:attachment":[{"href":"https:\/\/www.gardiso.eu\/de\/wp-json\/wp\/v2\/media?parent=2716"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.gardiso.eu\/de\/wp-json\/wp\/v2\/product_cat?post=2716"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.gardiso.eu\/de\/wp-json\/wp\/v2\/product_tag?post=2716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}